{"id":1835,"date":"2025-07-04T07:55:45","date_gmt":"2025-07-04T07:55:45","guid":{"rendered":"https:\/\/www.worldpadelnetwork.com\/club\/%city%\/bapadel-barcelona\/"},"modified":"2025-07-04T07:55:45","modified_gmt":"2025-07-04T07:55:45","slug":"bapadel-barcelona","status":"publish","type":"club","link":"https:\/\/www.worldpadelnetwork.com\/ca\/club\/barcelona-ca\/bapadel-barcelona\/","title":{"rendered":"BaPadel Barcelona"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"}},"city":[47],"class_list":["post-1835","club","type-club","status-publish","hentry","city-barcelona-ca"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.worldpadelnetwork.com\/ca\/wp-json\/wp\/v2\/club\/1835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldpadelnetwork.com\/ca\/wp-json\/wp\/v2\/club"}],"about":[{"href":"https:\/\/www.worldpadelnetwork.com\/ca\/wp-json\/wp\/v2\/types\/club"}],"version-history":[{"count":0,"href":"https:\/\/www.worldpadelnetwork.com\/ca\/wp-json\/wp\/v2\/club\/1835\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.worldpadelnetwork.com\/ca\/wp-json\/wp\/v2\/media?parent=1835"}],"wp:term":[{"taxonomy":"city","embeddable":true,"href":"https:\/\/www.worldpadelnetwork.com\/ca\/wp-json\/wp\/v2\/city?post=1835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}